{"id":10222,"date":"2025-03-02T12:27:22","date_gmt":"2025-03-02T12:27:22","guid":{"rendered":"https:\/\/truespecgolf.com\/chelsea-piers\/bahamas-copy\/"},"modified":"2026-03-03T16:10:48","modified_gmt":"2026-03-03T16:10:48","slug":"nyc-chelsea-piers","status":"publish","type":"page","link":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/","title":{"rendered":"NYC Chelsea Piers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10222\" class=\"elementor elementor-10222\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae9d424 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ae9d424\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-285ebd9\" data-id=\"285ebd9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac5e625 elementor-widget elementor-widget-template\" data-id=\"ac5e625\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8600\" class=\"elementor elementor-8600\" data-elementor-settings=\"[]\">\n\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5598eeaa elementor-section-full_width elementor-section-height-min-height location-hero elementor-hidden-phone elementor-section-height-default elementor-section-items-middle\" data-id=\"5598eeaa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3924ff2d\" data-id=\"3924ff2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-202fac7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"202fac7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-212909df\" data-id=\"212909df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a2ae847 elementor-widget elementor-widget-heading\" data-id=\"5a2ae847\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NYC Chelsea Piers<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54df944d elementor-widget-mobile__width-inherit elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-button\" data-id=\"54df944d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"\/get-fit\/\" class=\"elementor-button-link elementor-button elementor-size-lg\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eebb7c5 elementor-widget elementor-widget-shortcode\" data-id=\"eebb7c5\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n    <div class=\"table-container\">\n        <div class=\"table-item table-item--address\">\n            <div class=\"table-heading table-heading--address\">\n                <p>Address<\/p>\n            <\/div>\n            <div class=\"table-text table-text--address\">\n                <p><strong>True Spec Golf<\/strong><\/p>\n<p class=\"x_MsoNormal\">59 Chelsea Piers<\/p>\n<p class=\"x_MsoNormal\">New York, NY 10011<\/p>\n            <\/div>\n            \n        <\/div>\n\n        <div class=\"table-item\">\n            <div class=\"table-heading\">\n                <p>Hours<\/p>\n            <\/div>\n            <div class=\"table-text\">\n                <p><b><span data-olk-copy-source=\"MessageBody\">9am-8pm<\/span><\/b><span class=\"x_apple-converted-space\">\u00a0<\/span>(Tues)<\/p>\n<p><strong>9am-4:30pm<\/strong> (Wed)<\/p>\n<p><strong>9am-5pm<\/strong> (Thurs-Sat)<\/p>\n<p>By Appointment Only<\/p>\n            <\/div>\n            \n        <\/div>\n\n        <div class=\"table-item\">\n            <div class=\"table-heading\">\n                <p>Location Style<\/p>\n            <\/div>\n            <div class=\"table-text\">\n                Indoor            <\/div>\n            \n        <\/div>\n\n        <div class=\"table-item\">\n            <div class=\"table-heading\">\n                <p># of Bays<\/p>\n            <\/div>\n            <div class=\"table-text\">\n                1 Fitting Bay            <\/div>\n            \n        <\/div>\n        \n    <\/div>\n\n    \t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24be607 w-100 elementor-hidden-desktop elementor-widget elementor-widget-button\" data-id=\"24be607\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"\/get-fit\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Book Now<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52b37f24 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52b37f24\" data-element_type=\"section\" id=\"location_hero_mobile\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59ff897d\" data-id=\"59ff897d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ef8bd1b elementor-widget elementor-widget-heading\" data-id=\"1ef8bd1b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">NYC Chelsea Piers<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb65eca elementor-widget elementor-widget-shortcode\" data-id=\"1cb65eca\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"location_address_mobile\"><p><strong>True Spec Golf<\/strong><\/p>\n<p class=\"x_MsoNormal\">59 Chelsea Piers<\/p>\n<p class=\"x_MsoNormal\">New York, NY 10011<\/p>\n<\/div>\r\n    \t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4744e553 elementor-section-full_width elementor-section-height-min-height location-hero elementor-section-content-bottom elementor-section-height-default\" data-id=\"4744e553\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6c4bc405\" data-id=\"6c4bc405\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60f51a69 w-100 elementor-hidden-desktop elementor-widget elementor-widget-button\" data-id=\"60f51a69\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"\/get-fit\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Schedule Now<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-50041bb9 elementor-widget elementor-widget-shortcode\" data-id=\"50041bb9\" data-element_type=\"widget\" id=\"locaton_details\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\r\n\t<div class=\"location_details_single\">\r\n\t\t<div class=\"location_details_single_inner location_details_single_inner_label\">Hours:<\/div>\r\n\t\t<div class=\"location_details_single_inner location_details_single_inner_data\"><p><b><span data-olk-copy-source=\"MessageBody\">9am-8pm<\/span><\/b><span class=\"x_apple-converted-space\">\u00a0<\/span>(Tues)<\/p>\n<p><strong>9am-4:30pm<\/strong> (Wed)<\/p>\n<p><strong>9am-5pm<\/strong> (Thurs-Sat)<\/p>\n<p>By Appointment Only<\/p>\n<\/div>\r\n\t<\/div>\r\n\t<div class=\"location_details_single\">\r\n\t\t<div class=\"location_details_single_inner location_details_single_inner_label\">Location Style:<\/div>\r\n\t\t<div class=\"location_details_single_inner location_details_single_inner_data\">Indoor<\/div>\r\n\t<\/div>\r\n\t<div class=\"location_details_single\">\r\n\t\t<div class=\"location_details_single_inner location_details_single_inner_label\"># of Bays:<\/div>\r\n\t\t<div class=\"location_details_single_inner location_details_single_inner_data\">1 Fitting Bay<\/div>\r\n\t<\/div>\r\n    \t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36b2295 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36b2295\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1529872\" data-id=\"1529872\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c4d96fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4d96fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-533ff7f\" data-id=\"533ff7f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4a0c9 elementor-widget elementor-widget-shortcode\" data-id=\"7a4a0c9\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"itemsContentSection\"><div class=\"itemsContentSection__wrap\"><div class=\"itemsContentSection__items\"><div class=\"itemsContentSection__items__image\"><img loading=\"lazy\" decoding=\"async\" width=\"535\" height=\"301\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TSG-NYC-Chelsea-Piers-About.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TSG-NYC-Chelsea-Piers-About.jpg 535w, https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TSG-NYC-Chelsea-Piers-About-300x169.jpg 300w\" sizes=\"auto, (max-width: 535px) 100vw, 535px\" \/> <\/div><div class=\"itemsContentSection__items__content\"><h3><strong>About<\/strong><\/h3>\n<p><span data-olk-copy-source=\"MessageBody\">Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology. True Spec NYC Chelsea Piers also features our signature brand-agnostic club fitting matrix of over 70,000 clubhead and shaft combinations which helps our master club fitters identify the best equipment to improve your golf game.<\/span><\/p>\n <\/div> <\/div><div class=\"itemsContentSection__items\" style=\"flex-direction: row-reverse;\"><div class=\"itemsContentSection__items__image\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/The-Golf-Club-at-CP-About-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/The-Golf-Club-at-CP-About-768x513.jpg 768w, https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/The-Golf-Club-at-CP-About-300x200.jpg 300w, https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/The-Golf-Club-at-CP-About-600x401.jpg 600w, https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/The-Golf-Club-at-CP-About.jpg 900w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/> <\/div><div class=\"itemsContentSection__items__content\"><p><strong>The Golf Club at Chelsea Piers \u2013 NEW YORK, NY<\/strong><\/p>\n<p class=\"x_MsoNormal\"><a title=\"Original URL: https:\/\/sports.chelseapiers.com\/new-york\/chelsea\/sports\/golf. Click or tap if you trust this link.\" href=\"https:\/\/nam12.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fsports.chelseapiers.com%2Fnew-york%2Fchelsea%2Fsports%2Fgolf&amp;data=05%7C02%7CMichael.Anderson%40fairwayjockey.com%7C41f9c9e9496a4dcbe7fe08dd5840b7d6%7Ced9ac16c4f2d4460903ec64550d44b11%7C0%7C0%7C638763757196272419%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&amp;sdata=%2BulkG6HS%2BXr8dSke2R8PTrngCyJ6QawXLpc8jjI25RY%3D&amp;reserved=0\" data-auth=\"NotApplicable\" data-linkindex=\"2\">The Golf Club at Chelsea Piers<\/a>\u00a0is home to the most popular golf driving range in New York City. They offer driving range sessions with Inrange technology, private and semi-private lessons, youth and adult golf clinics, summer camps, Full Swing simulators, and the Water Hazard Bar + Lounge. Enjoy golf year-round with heated and weather-protected stalls, as well as an automatic ball tee-up system.<\/p>\n <\/div> <\/div> <\/div> <\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-90c9e96 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90c9e96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72744be\" data-id=\"72744be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-194a611 elementor-widget elementor-widget-image\" data-id=\"194a611\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TSG-NYC-Chelsea-Piers-About.jpg\" title=\"\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1033d9e\" data-id=\"1033d9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-825c7b3 location-header elementor-widget elementor-widget-text-editor\" data-id=\"825c7b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><h3><strong>About<\/strong><\/h3>\n<p><span data-olk-copy-source=\"MessageBody\">Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology. True Spec NYC Chelsea Piers also features our signature brand-agnostic club fitting matrix of over 70,000 clubhead and shaft combinations which helps our master club fitters identify the best equipment to improve your golf game.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2466edd fitting-types-6-in-row elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2466edd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd6f08f\" data-id=\"dd6f08f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3468ed9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3468ed9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-884f1ac\" data-id=\"884f1ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a5a239 elementor-widget elementor-widget-heading\" data-id=\"7a5a239\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fitting Types<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc98bff elementor-widget elementor-widget-shortcode\" data-id=\"dc98bff\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"fitting-types__container\">\n        \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/tsg-fitting-icons_Full-Bag.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Full Bag<\/p>\n                                                             <p class=\"fitting-types__time\">2.5 hrs<\/p>\n                                                             <p class=\"fitting-types__price\">$375<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">Everything but the putter. You\u2019re rolling it just fine<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/tsg-fitting-icons_Woods.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Woods<\/p>\n                                                             <p class=\"fitting-types__time\">2 hrs<\/p>\n                                                             <p class=\"fitting-types__price\">$275<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">Just the top of the bag. Driver, fairway woods & hybrids<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2024\/06\/tsg-fitting-icons_iron-Driver42.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Driver & Iron<\/p>\n                                                             <p class=\"fitting-types__time\">2 hrs<\/p>\n                                                             <p class=\"fitting-types__price\">$275<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">Upgrade your driver & irons only<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/tsg-fitting-icons_Irons-Wedge.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Iron & Wedge<\/p>\n                                                             <p class=\"fitting-types__time\">2 hrs<\/p>\n                                                             <p class=\"fitting-types__price\">$225<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">Better fit, better ball striking. Find what works for you<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/tsg-fitting-icons_driver.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Driver<\/p>\n                                                             <p class=\"fitting-types__time\">1 hr<\/p>\n                                                             <p class=\"fitting-types__price\">$175<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">More distance? Better accuracy? Find the right big stick for you<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2022\/01\/Tsg-fitting-icons-fairway_hybrid.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Fairway & Hybrid<\/p>\n                                                             <p class=\"fitting-types__time\">1 hr<\/p>\n                                                             <p class=\"fitting-types__price\">$175<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">All woods & hybrids but no need for driver change<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/tsg-fitting-icons_irons.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Iron<\/p>\n                                                             <p class=\"fitting-types__time\">1 hr<\/p>\n                                                             <p class=\"fitting-types__price\">$175<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">More forgiveness? Better feel? Find the right iron set for you<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2022\/01\/tsg-fitting-icons-wedge.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Wedge<\/p>\n                                                             <p class=\"fitting-types__time\">1 hr<\/p>\n                                                             <p class=\"fitting-types__price\">$125<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">Dial in your \u201cscoring\u201d clubs to snug closer to pins<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/tsg-fitting-icons_gap-analysis.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Gap Analysis<\/p>\n                                                             <p class=\"fitting-types__time\">1 hr<\/p>\n                                                             <p class=\"fitting-types__price\">$125<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">Fitting provides loft & lie data of existing clubs<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                      \n                                    <div class=\"fitting-types__item hover-rotate-card\">\n             <div class=\"fitting-types__items\">\n              <div class=\"fitting-types__item__front\">\n                <div class=\"fitting-types__item__head\">\n                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/tsg-fitting-icons_shaft-only.png\" alt=\"\">\n                    <\/div>\n                    <div class=\"fitting-types__item__body\">\n                                         <p class=\"fitting-types__title\">Shaft Only<\/p>\n                                                             <p class=\"fitting-types__time\">1 hr<\/p>\n                                                             <p class=\"fitting-types__price\">$125<\/p>\n                                        <\/div>\n                 <\/div>\n                      <div class=\"fitting-types__item__back\">\n                                    <p class=\"fitting-types__description\">Retrofit existing club with new shaft<\/p>\n\n              <\/div>\n              <\/div>\n              <\/div>\n                          <\/div>\n    \t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fea61a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1fea61a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4007335\" data-id=\"4007335\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9593d79 elementor-section-full_width elementer-gallery-templet elementor-section-height-default elementor-section-height-default\" data-id=\"9593d79\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5bc10e3\" data-id=\"5bc10e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-869676a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"869676a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dea676\" data-id=\"7dea676\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bfdc12 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"8bfdc12\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t<div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8bfdc12\" data-elementor-lightbox-title=\"TrueSpec Chelsea-Gallery4\" href=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery4.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery4.jpg\" alt=\"TrueSpec Chelsea-Gallery4\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8bfdc12\" data-elementor-lightbox-title=\"TrueSpec Chelsea Gallery-2\" href=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-2.jpg\" alt=\"TrueSpec Chelsea Gallery-2\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8bfdc12\" data-elementor-lightbox-title=\"TrueSpec Chelsea Gallery-3\" href=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-3.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-3.jpg\" alt=\"TrueSpec Chelsea Gallery-3\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8bfdc12\" data-elementor-lightbox-title=\"TrueSpec Chelsea Gallery-4\" href=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-4.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-4.jpg\" alt=\"TrueSpec Chelsea Gallery-4\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8bfdc12\" data-elementor-lightbox-title=\"TrueSpec Chelsea Gallery-5\" href=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-5.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/03\/TrueSpec-Chelsea-Gallery-5.jpg\" alt=\"TrueSpec Chelsea Gallery-5\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i class=\"eicon-chevron-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i class=\"eicon-chevron-right\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3dd648 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3dd648\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd0ba08\" data-id=\"bd0ba08\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a38f2bd elementor-widget elementor-widget-shortcode\" data-id=\"a38f2bd\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">    <script type=\"text\/javascript\">\n    var ajaxurl = 'https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-admin\/admin-ajax.php';\n    var bir_business_id = '174101730221708';\n    <\/script>\n    <style type=\"text\/css\"><\/style>\n\n        <div class=\"review-wrapper\">\n            <div class=\"reviews-heading\">\n                <h2 class=\"reviews-heading-title\">Customer Reviews<\/h2>\n            <\/div>\n            <div class=\"grid grid--1of3\">\n                <section class=\"grid-cell left\">\n                    <div class=\"\">\n                                        \n\n                            <div class=\"avg-rating-block\">\n                                                                <div class=\"bew-avgstars bf-brand-color \">\n\n                                    <div class=\"stars-avg-rating\">\n                                        <span class=\"be-c-star\">\n                                            <span class=\"starOn\"><img src=https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-big.svg><\/span>\n                                        <\/span><span class=\"be-c-star\">\n                                            <span class=\"starOn\"><img src=https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-big.svg><\/span>\n                                        <\/span><span class=\"be-c-star\">\n                                            <span class=\"starOn\"><img src=https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-big.svg><\/span>\n                                        <\/span><span class=\"be-c-star\">\n                                            <span class=\"starOn\"><img src=https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-big.svg><\/span>\n                                        <\/span><span class=\"be-c-star\">\n                                            <span class=\"starOn\"><img src=https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-big.svg><\/span>\n                                        <\/span>                                    <\/div>\n                                <\/div>\n                                <div class=\"avg-rating-values\">\n\n                                    <div class=\"avg-ratingval\"> 5.0<\/div>\n                                    <div class=\"avg-rating-count filter-by-rating\" data-rating=\"\">(68 reviews)<\/div>\n                               <\/div>\n                            <\/div>\n                            <hr class=\"hidden-xs\">\n                            <div class=\"review-summary\">\n\n                                <div class=\"reviews-left-column-heading\">\n                                    Summary :\n                                <\/div>\n\n                                                               <div class=\"stars-line\">\n\n                               <div class=\"star-line-stars\">\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                                                         <\/div>\n                               <div class=\"star-line-count filter-by-rating\"  data-rating=\"5\">68<\/div>\n                               <\/div>\n\n\n                                                                   <div class=\"stars-line\">\n\n                               <div class=\"star-line-stars\">\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                          \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                                                              <\/div>\n                               <div class=\"star-line-count filter-by-rating\"  data-rating=\"4\">0<\/div>\n                               <\/div>\n\n\n                                                                   <div class=\"stars-line\">\n\n                               <div class=\"star-line-stars\">\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                          \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                               \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                                                              <\/div>\n                               <div class=\"star-line-count filter-by-rating\"  data-rating=\"3\">0<\/div>\n                               <\/div>\n\n\n                                                                   <div class=\"stars-line\">\n\n                               <div class=\"star-line-stars\">\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                          \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                               \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                               \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                                                              <\/div>\n                               <div class=\"star-line-count filter-by-rating\"  data-rating=\"2\">0<\/div>\n                               <\/div>\n\n\n                                                                   <div class=\"stars-line\">\n\n                               <div class=\"star-line-stars\">\n                           \n                               <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                          \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                               \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                               \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                               \n                                   <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-passive-new.svg\">\n                                                <\/span>\n                                                              <\/div>\n                               <div class=\"star-line-count filter-by-rating\"  data-rating=\"1\">0<\/div>\n                               <\/div>\n\n\n                                                    <\/div>\n                            <hr class=\"hidden-xs\">\n\n\n\n\n\n        <div class=\"hidden-xs\">\n            <div class=\"reviews-sources\">\n                <div class=\"reviews-left-column-heading\">\n                    View by source :\n                <\/div>\n                  <div class=\"reviews-source\"><input type=\"checkbox\" name=\"reviews-filter\" value=\"all\"> All<\/div><div class=\"reviews-source\"><input type=\"checkbox\" name=\"reviews-filter\" value=\"google\"> Google<span> (68)<\/span><\/div>            <\/div>\n\n        <\/div>\n\n\n            \n        <\/section>\n\n        <section class=\"grid-cell rights\" id=\"Reviews_Container\">\n        <div class=\"visible-xs\">\n                <select name=\"selectSource\" class=\"selectSource\">\n                    <option value=\"\" selected>View all sources<\/option><option value=\"google\">Google (68)                <\/select>\n            <\/div>\n\n            <div class=\"actionButtonWrapper new-button-wrapper\">\n                                <a id=\"btnWriteAReview\" href=\"https:\/\/birdeye.com\/true spec golf - nyc chelsea piers-174101730221708\/mobile\" class=\"\" target=\"_blank\">\n                        + Add Review\n                    <\/a>                            <\/div>\n    <div class=\"block\">\n\n            <article class=\"review-content\">\n            <div class=\"review-heading\">\n                <div class=\"review-person-name\">Dan<\/div>\n                <div class=\"review-date\">\n                    05\/09\/2026                <\/div>\n            <\/div>\n            <div class=\"review-subheading\">\n                <div class=\"review-source\">\n                    Source: <a target=_blank class=\"review-source-link\" href=\"https:\/\/www.google.com\/maps\/place\/?cid=654018039771971669&place_id=ChIJsQ_H9BxZwokRVUBOKfGJEwk\">\n                        <span class=\"brand\">Google<\/a>\n                <\/div>\n                <div class=\"review-rating\">\n                    <div class=\"review-rating-value\">5\/5<\/div>\n                    <div class=\"star-line-stars\">\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"review-content-content\">\n                It was great. Patrick was super knowledgeable and helpful. He was thoughtful and efficient.            <\/div>\n            <\/article>\n            <hr>\n               <article class=\"review-content\">\n            <div class=\"review-heading\">\n                <div class=\"review-person-name\">Daniel<\/div>\n                <div class=\"review-date\">\n                    05\/08\/2026                <\/div>\n            <\/div>\n            <div class=\"review-subheading\">\n                <div class=\"review-source\">\n                    Source: <a target=_blank class=\"review-source-link\" href=\"https:\/\/www.google.com\/maps\/place\/?cid=654018039771971669&place_id=ChIJsQ_H9BxZwokRVUBOKfGJEwk\">\n                        <span class=\"brand\">Google<\/a>\n                <\/div>\n                <div class=\"review-rating\">\n                    <div class=\"review-rating-value\">5\/5<\/div>\n                    <div class=\"star-line-stars\">\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"review-content-content\">\n                            <\/div>\n            <\/article>\n            <hr>\n               <article class=\"review-content\">\n            <div class=\"review-heading\">\n                <div class=\"review-person-name\">David<\/div>\n                <div class=\"review-date\">\n                    05\/07\/2026                <\/div>\n            <\/div>\n            <div class=\"review-subheading\">\n                <div class=\"review-source\">\n                    Source: <a target=_blank class=\"review-source-link\" href=\"https:\/\/www.google.com\/maps\/place\/?cid=654018039771971669&place_id=ChIJsQ_H9BxZwokRVUBOKfGJEwk\">\n                        <span class=\"brand\">Google<\/a>\n                <\/div>\n                <div class=\"review-rating\">\n                    <div class=\"review-rating-value\">5\/5<\/div>\n                    <div class=\"star-line-stars\">\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                        \n                            <span class=\"starOn\">\n                                                    <img decoding=\"async\" src=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/plugins\/bird-eye-reviews\/images\/star-active-new.svg\">\n                                                <\/span>\n                                                                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"review-content-content\">\n                Could not have had a better first fitting at the Chelsea Piers True Spec location with Patrick. He was super helpful and honest. Will definitely be back            <\/div>\n            <\/article>\n            <hr>\n               <\/div>\n    <\/section>\n    <\/div>\n    <\/div>\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06206bc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"06206bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33b03fb\" data-id=\"33b03fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4b8a9a elementor-widget elementor-widget-template\" data-id=\"e4b8a9a\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10181\" class=\"elementor elementor-10181\" data-elementor-settings=\"[]\">\n\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c1f6eed elementor-section-full_width location-form-section elementor-section-height-default elementor-section-height-default\" data-id=\"7c1f6eed\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-222641ed\" data-id=\"222641ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12486a95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12486a95\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-daeb04a\" data-id=\"daeb04a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62a241c8 elementor-widget elementor-widget-heading\" data-id=\"62a241c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ready To Get Fit?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77199b35 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"77199b35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6358a9 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"c6358a9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a class=\"elementor-icon elementor-animation-\" href=\"tel:+18447298809\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"tel:+18447298809\">+1 844 729 8809<\/a>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1279c2d5 elementor-position-left elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"1279c2d5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a class=\"elementor-icon elementor-animation-\" href=\"mailto:info@truespecgolf.com\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<a href=\"mailto:info@truespecgolf.com\">info@truespecgolf.com<\/a>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7cc29df0\" data-id=\"7cc29df0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7408cc2 elementor-widget elementor-widget-shortcode\" data-id=\"7408cc2\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f9157-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/nyc-chelsea-piers\/wp-json\/wp\/v2\/pages\/10222#wpcf7-f9157-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"9157\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9157-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"contact-field-wrapper \"><label class=\"contact-field-label\" for=\"firstname\">First Name <span>*<\/span><\/label><span class=\"wpcf7-form-control-wrap firstname\"><input type=\"text\" name=\"firstname\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required contact-field contact-field--black\" id=\"firstname\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><\/div>\n<div class=\"contact-field-wrapper\"><label class=\"contact-field-label\" for=\"lastname\">Last Name <span>*<\/span><\/label><span class=\"wpcf7-form-control-wrap lastname\"><input type=\"text\" name=\"lastname\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required contact-field contact-field--black\" id=\"lastname\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><\/div>\n<div class=\"contact-field-wrapper\"><label class=\"contact-field-label\" for=\"email-356\">Email address <span>*<\/span><\/label><span class=\"wpcf7-form-control-wrap email-356\"><input type=\"email\" name=\"email-356\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email contact-field contact-field--black\" id=\"email-356\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><\/div>\n<div class=\"contact-field-wrapper\"><input type=\"submit\" value=\"Get Started\" class=\"wpcf7-form-control wpcf7-submit contact-submit location-btn\" \/><\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Previous Next<\/p>\n","protected":false},"author":2,"featured_media":11515,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"location-individual-page.php","meta":{"footnotes":""},"class_list":["post-10222","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>True Spec Golf - Club Fitting Locations | NYC Chelsea Piers<\/title>\n<meta name=\"description\" content=\"Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"True Spec Golf - Club Fitting Locations | NYC Chelsea Piers\" \/>\n<meta property=\"og:description\" content=\"Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\" \/>\n<meta property=\"og:site_name\" content=\"NYC Chelsea Piers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T16:10:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TSG-NYC-Chelsea-Piers-About.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"535\" \/>\n\t<meta property=\"og:image:height\" content=\"301\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"True Spec Golf - Club Fitting Locations | NYC Nexus\" \/>\n<meta name=\"twitter:description\" content=\"Located in lower Manhattan at Barclay and Church Street near Fulton Street Subway station, True Spec NYC NEXUS includes a spacious indoor club fitting bay and a world-class putting studio.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2021\/01\/nyc_nexus-location.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\",\"url\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\",\"name\":\"True Spec Golf - Club Fitting Locations | NYC Chelsea Piers\",\"isPartOf\":{\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TrueSpec-Chelsea-Hero.jpg\",\"datePublished\":\"2025-03-02T12:27:22+00:00\",\"dateModified\":\"2026-03-03T16:10:48+00:00\",\"description\":\"Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology.\",\"breadcrumb\":{\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#primaryimage\",\"url\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TrueSpec-Chelsea-Hero.jpg\",\"contentUrl\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TrueSpec-Chelsea-Hero.jpg\",\"width\":2200,\"height\":1467,\"caption\":\"NYC Chelsea Piers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NYC Chelsea Piers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#website\",\"url\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\",\"name\":\"NYC Chelsea Piers\",\"description\":\"True Spec Golf\",\"publisher\":{\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#organization\",\"name\":\"NYC Chelsea Piers\",\"url\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/logo.svg\",\"contentUrl\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/logo.svg\",\"width\":179,\"height\":50,\"caption\":\"NYC Chelsea Piers\"},\"image\":{\"@id\":\"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"True Spec Golf - Club Fitting Locations | NYC Chelsea Piers","description":"Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/","og_locale":"en_US","og_type":"article","og_title":"True Spec Golf - Club Fitting Locations | NYC Chelsea Piers","og_description":"Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology.","og_url":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/","og_site_name":"NYC Chelsea Piers","article_modified_time":"2026-03-03T16:10:48+00:00","og_image":[{"width":535,"height":301,"url":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TSG-NYC-Chelsea-Piers-About.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"True Spec Golf - Club Fitting Locations | NYC Nexus","twitter_description":"Located in lower Manhattan at Barclay and Church Street near Fulton Street Subway station, True Spec NYC NEXUS includes a spacious indoor club fitting bay and a world-class putting studio.","twitter_image":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2021\/01\/nyc_nexus-location.jpg","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/","url":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/","name":"True Spec Golf - Club Fitting Locations | NYC Chelsea Piers","isPartOf":{"@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#website"},"primaryImageOfPage":{"@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#primaryimage"},"image":{"@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#primaryimage"},"thumbnailUrl":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TrueSpec-Chelsea-Hero.jpg","datePublished":"2025-03-02T12:27:22+00:00","dateModified":"2026-03-03T16:10:48+00:00","description":"Located inside The Golf Club at Chelsea Piers, True Spec NYC Chelsea Piers includes a spacious indoor club fitting bay and utilizes industry-leading launch monitor technology.","breadcrumb":{"@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truespecgolf.com\/nyc-chelsea-piers\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#primaryimage","url":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TrueSpec-Chelsea-Hero.jpg","contentUrl":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2025\/02\/TrueSpec-Chelsea-Hero.jpg","width":2200,"height":1467,"caption":"NYC Chelsea Piers"},{"@type":"BreadcrumbList","@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/"},{"@type":"ListItem","position":2,"name":"NYC Chelsea Piers"}]},{"@type":"WebSite","@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#website","url":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/","name":"NYC Chelsea Piers","description":"True Spec Golf","publisher":{"@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#organization","name":"NYC Chelsea Piers","url":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#\/schema\/logo\/image\/","url":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/logo.svg","contentUrl":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-content\/uploads\/sites\/45\/2020\/12\/logo.svg","width":179,"height":50,"caption":"NYC Chelsea Piers"},"image":{"@id":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/pages\/10222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/comments?post=10222"}],"version-history":[{"count":0,"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/pages\/10222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/media\/11515"}],"wp:attachment":[{"href":"https:\/\/truespecgolf.com\/nyc-chelsea-piers\/wp-json\/wp\/v2\/media?parent=10222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}